{"id":1403,"date":"2026-05-05T10:01:08","date_gmt":"2026-05-05T09:01:08","guid":{"rendered":"https:\/\/lacanquotidien.org\/?p=1403"},"modified":"2026-05-06T09:01:18","modified_gmt":"2026-05-06T08:01:18","slug":"lacan-quotidien-n43-probleme-de-vocabulaire-par-lionel-menon","status":"publish","type":"post","link":"https:\/\/lacanquotidien.org\/index.php\/2026\/05\/05\/lacan-quotidien-n43-probleme-de-vocabulaire-par-lionel-menon\/","title":{"rendered":"Lacan Quotidien n\u00b043 \u2013 Probl\u00e8me de vocabulaire, par Lionel M\u00e9non"},"content":{"rendered":"\n<p class=\"has-text-align-center\">N\u00b043<br><mark style=\"background-color:rgba(0, 0, 0, 0);color:#f9610f\" class=\"has-inline-color\"><a href=\"https:\/\/lacanquotidien.org\/index.php\/2026\/05\/05\/lacan-quotidien-n43-temoignage-de-precision-par-patricia-wartelle\/\">T\u00e9moignage de pr\u00e9cision,<\/a> <\/mark>par Patricia Wartelle<\/p>\n\n\n\n<p class=\"has-text-align-center\"><mark style=\"background-color:rgba(0, 0, 0, 0);color:#f9610f\" class=\"has-inline-color\"><a href=\"https:\/\/lacanquotidien.org\/index.php\/2026\/05\/05\/lacan-quotidien-n43-probleme-de-vocabulaire-par-lionel-menon\/\">Probl\u00e8me de vocabulaire<\/a><\/mark>, par Lionel M\u00e9non<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"677\" height=\"29\" src=\"https:\/\/lacanquotidien.org\/wp-content\/uploads\/2026\/01\/Tiret-1.jpg\" alt=\"\" class=\"wp-image-834\" style=\"width:300px\" srcset=\"https:\/\/lacanquotidien.org\/wp-content\/uploads\/2026\/01\/Tiret-1.jpg 677w, https:\/\/lacanquotidien.org\/wp-content\/uploads\/2026\/01\/Tiret-1-300x13.jpg 300w\" sizes=\"auto, (max-width: 677px) 100vw, 677px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"has-text-align-center\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0);color:#f9610f\" class=\"has-inline-color\">Probl\u00e8me de vocabulaire<\/mark><\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center\"><em>Lionel M\u00e9non<\/em><\/p>\n\n\n\n<p>La pratique dans notre Institut th\u00e9rapeutique, \u00e9ducatif et p\u00e9dagogique (ITEP) nous conduit parfois \u00e0 proposer ou r\u00e9pondre \u00e0 la demande d\u2019une r\u00e9union consacr\u00e9e \u00e0 l\u2019\u00e9volution d\u2019un enfant en pr\u00e9sence de son enseignant(e), de son accompagnant(e) (AESH) et de ses parents. Un membre de la direction, de l\u2019assistance sociale et de l\u2019\u00e9quipe de psychologues respectivement se rendent alors dans l\u2019\u00e9tablissement scolaire de l\u2019enfant.<\/p>\n\n\n\n<p>C\u2019est le cas, ce matin de mars 2025, quand un appel t\u00e9l\u00e9phonique de la secr\u00e9taire nous demande de revenir de toute urgence dans les murs, \u00e0 8h45. Une d\u00e9l\u00e9gation de l\u2019Agence r\u00e9gionale de Sant\u00e9 (ARS) vient d\u2019arriver dans l\u2019institution dans le cadre d\u2019une visite, dite \u00abinopin\u00e9e\u00bb, qui doit durer trois jours.<\/p>\n\n\n\n<p><strong><mark style=\"background-color:rgba(0, 0, 0, 0);color:#f9610f\" class=\"has-inline-color\">Inspection<\/mark><\/strong><\/p>\n\n\n\n<p>Le motif de cette inspection n\u2019est pas d\u00e9clar\u00e9 et, \u00e0 la suite de nos demandes, appara\u00eet allusif ou confus, allant de la proc\u00e9dure de routine \u00e0 la plainte anonymis\u00e9e signalant l\u2019existence de risques pour la sant\u00e9 des enfants. L\u2019heure est grave. Il s\u2019av\u00e8re que l\u2019institution o\u00f9 j\u2019exerce comme psychologue, en plus d\u2019\u00eatre l\u2019une des derni\u00e8res \u00e0 n\u2019\u00eatre pas rattach\u00e9e \u00e0 une grande association reconnue du territoire, b\u00e9n\u00e9ficie d\u2019une r\u00e9putation de structure orient\u00e9e globalement par la psychanalyse.<\/p>\n\n\n\n<p>Les salles sont ouvertes, les tiroirs fouill\u00e9s. Tout le personnel administratif est r\u00e9quisitionn\u00e9. Cinq acteurs de terrain sont d\u00e9sign\u00e9s pour \u00eatre entendus individuellement par les inspecteurs. Au titre de psychologue, j\u2019en suis. On me demande de signer une autorisation d\u2019\u00eatre enregistr\u00e9 par un petit boitier contenant une IA qui synth\u00e9tisera mes propos, et destin\u00e9 \u00e0 rendre mes interlocuteurs \u00abplus pr\u00e9sents dans l\u2019entretien\u00bb, avancent-ils. Je signe. Suite aux pr\u00e9sentations respectives, je m\u2019autorise \u00e0 demander la sp\u00e9cialit\u00e9 m\u00e9dicale d\u2019une de mes interlocutrices: \u00abP\u00e9dopsychiatre, je suppose?\u00bb Silence. \u00abNon\u2026 anesth\u00e9siste\u2026\u00bb. Silence. Nous apprendrons deux mois plus tard que cette interlocutrice a d\u00e9missionn\u00e9 de ce poste d\u2019agent de l\u2019ARS. Effet de honte? Quelle question s\u2019est pos\u00e9e pour elle? Elle seule le sait. Participer \u00e0 de telles missions n\u2019est sans doute pas sans cons\u00e9quences pour chacun. La conversation sera courtoise, mes propos tr\u00e8s \u00e9cout\u00e9s.<\/p>\n\n\n\n<p>On me demande en fin d\u2019entretien de confirmer qu\u2019il n\u2019y a aucune pratique de contention dans l\u2019institution. Je confirme et ajoute: \u00abEnfin\u2026 quand un enfant en frappe un autre violemment ou qu\u2019un enfant enjambe une fen\u00eatre situ\u00e9e \u00e0 l\u2019\u00e9tage, on le retient quand m\u00eame.\u00bb Mes interlocutrices, visiblement impressionn\u00e9es d\u2019une telle possibilit\u00e9, acquiescent avec un air d\u2019\u00e9vidence.<\/p>\n\n\n\n<p><strong><mark style=\"background-color:rgba(0, 0, 0, 0);color:#f9610f\" class=\"has-inline-color\">\u00c9couter n\u2019est pas entendre<\/mark><\/strong><\/p>\n\n\n\n<p>En fin de semaine, un premier retour oral nous sera fait, disant textuellement ceci: \u00abVous n\u2019arr\u00eatez pas de parler de clinique! La clinique, c\u2019est fini! En trois jours, nous n\u2019avons jamais entendu les mots \u201cautod\u00e9termination\u201d, \u201cparentalit\u00e9\u201d, \u201cusager\u201d. Nous avons pourtant not\u00e9 que les gens semblent tr\u00e8s investis dans leur travail ici\u2026 Mais vous n\u2019avez pas le bon vocabulaire!\u00bb Cette injonction administrative, totalement indiff\u00e9rente aux pratiques professionnelles et ignorante des probl\u00e9matiques m\u00eames des enfants, nous demande de nous taire au profit d\u2019une autre langue.&nbsp;<\/p>\n\n\n\n<p>Nous r\u00e9sistons et ne c\u00e8derons pas sur les mots. Ni sur les n\u00f4tres, au plus proche des d\u00e9couvertes de notre praxis. Ni sur les mots que les enfants nous donnent \u00e0 entendre.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>N\u00b043T\u00e9moignage de pr\u00e9cision, par Patricia Wartelle Probl\u00e8me de vocabulaire, par Lionel M\u00e9non Probl\u00e8me de vocabulaire Lionel M\u00e9non La pratique dans notre Institut th\u00e9rapeutique, \u00e9ducatif et p\u00e9dagogique (ITEP) nous conduit parfois \u00e0 proposer ou r\u00e9pondre \u00e0 la demande d\u2019une r\u00e9union consacr\u00e9e \u00e0 l\u2019\u00e9volution d\u2019un enfant en pr\u00e9sence de son enseignant(e), de son accompagnant(e) (AESH) et de [&hellip;]<\/p>\n","protected":false},"author":78,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":57,"footnotes":""},"categories":[1],"tags":[231,344,345,346],"ppma_author":[352],"class_list":["post-1403","post","type-post","status-publish","format-standard","hentry","category-uncategorized","tag-controle","tag-inspection","tag-probleme","tag-vocabulaire"],"authors":[{"term_id":352,"user_id":78,"is_guest":0,"slug":"rodo","display_name":"Lionel M\u00e9non","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/3678c72abbeb54f7c89215d21b0aca62f68ebb3039cdcf7eec9c3f9e85b78b90?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/lacanquotidien.org\/index.php\/wp-json\/wp\/v2\/posts\/1403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lacanquotidien.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lacanquotidien.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lacanquotidien.org\/index.php\/wp-json\/wp\/v2\/users\/78"}],"replies":[{"embeddable":true,"href":"https:\/\/lacanquotidien.org\/index.php\/wp-json\/wp\/v2\/comments?post=1403"}],"version-history":[{"count":5,"href":"https:\/\/lacanquotidien.org\/index.php\/wp-json\/wp\/v2\/posts\/1403\/revisions"}],"predecessor-version":[{"id":1418,"href":"https:\/\/lacanquotidien.org\/index.php\/wp-json\/wp\/v2\/posts\/1403\/revisions\/1418"}],"wp:attachment":[{"href":"https:\/\/lacanquotidien.org\/index.php\/wp-json\/wp\/v2\/media?parent=1403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lacanquotidien.org\/index.php\/wp-json\/wp\/v2\/categories?post=1403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lacanquotidien.org\/index.php\/wp-json\/wp\/v2\/tags?post=1403"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/lacanquotidien.org\/index.php\/wp-json\/wp\/v2\/ppma_author?post=1403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}